{"id":257,"date":"2024-10-05T09:23:00","date_gmt":"2024-10-05T09:23:00","guid":{"rendered":"https:\/\/madeindex.org\/de\/?page_id=257"},"modified":"2024-10-05T09:23:00","modified_gmt":"2024-10-05T09:23:00","slug":"made-in-albania","status":"publish","type":"page","link":"https:\/\/madeindex.org\/de\/made-in-albania\/","title":{"rendered":"Made in Albania"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-257","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/madeindex.org\/de\/made-in-albania\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"MadeInDex - Der Nachhaltigkeitsindex\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Made in Albania - MadeInDex\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/madeindex.org\/de\/made-in-albania\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/madeindex.org\/de\/wp-content\/uploads\/2024\/09\/MadeInDex-Header-Logo.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/madeindex.org\/de\/wp-content\/uploads\/2024\/09\/MadeInDex-Header-Logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-10-05T09:23:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-10-05T09:23:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Made in Albania - MadeInDex\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/madeindex.org\/de\/wp-content\/uploads\/2024\/09\/MadeInDex-Header-Logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/madeindex.org\\\/de\\\/made-in-albania\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/madeindex.org\\\/de#listItem\",\"position\":1,\"name\":\"Zu Hause\",\"item\":\"https:\\\/\\\/madeindex.org\\\/de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/madeindex.org\\\/de\\\/made-in-albania\\\/#listItem\",\"name\":\"Made in Albania\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/madeindex.org\\\/de\\\/made-in-albania\\\/#listItem\",\"position\":2,\"name\":\"Made in Albania\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/madeindex.org\\\/de#listItem\",\"name\":\"Zu Hause\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/madeindex.org\\\/de\\\/#organization\",\"name\":\"MadeInDex\",\"description\":\"Der Nachhaltigkeitsindex\",\"url\":\"https:\\\/\\\/madeindex.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/madeindex.org\\\/de\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/MadeInDex-Header-Logo.png\",\"@id\":\"https:\\\/\\\/madeindex.org\\\/de\\\/made-in-albania\\\/#organizationLogo\",\"width\":177,\"height\":41,\"caption\":\"MadeInDex Logo\"},\"image\":{\"@id\":\"https:\\\/\\\/madeindex.org\\\/de\\\/made-in-albania\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/madeindex.org\\\/de\\\/made-in-albania\\\/#webpage\",\"url\":\"https:\\\/\\\/madeindex.org\\\/de\\\/made-in-albania\\\/\",\"name\":\"Made in Albania - MadeInDex\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/madeindex.org\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/madeindex.org\\\/de\\\/made-in-albania\\\/#breadcrumblist\"},\"datePublished\":\"2024-10-05T09:23:00+00:00\",\"dateModified\":\"2024-10-05T09:23:00+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/madeindex.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/madeindex.org\\\/de\\\/\",\"name\":\"MadeInDex\",\"description\":\"Der Nachhaltigkeitsindex\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/madeindex.org\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Made in Albania - MadeInDex","description":"","canonical_url":"https:\/\/madeindex.org\/de\/made-in-albania\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/madeindex.org\/de\/made-in-albania\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/madeindex.org\/de#listItem","position":1,"name":"Zu Hause","item":"https:\/\/madeindex.org\/de","nextItem":{"@type":"ListItem","@id":"https:\/\/madeindex.org\/de\/made-in-albania\/#listItem","name":"Made in Albania"}},{"@type":"ListItem","@id":"https:\/\/madeindex.org\/de\/made-in-albania\/#listItem","position":2,"name":"Made in Albania","previousItem":{"@type":"ListItem","@id":"https:\/\/madeindex.org\/de#listItem","name":"Zu Hause"}}]},{"@type":"Organization","@id":"https:\/\/madeindex.org\/de\/#organization","name":"MadeInDex","description":"Der Nachhaltigkeitsindex","url":"https:\/\/madeindex.org\/de\/","logo":{"@type":"ImageObject","url":"https:\/\/madeindex.org\/de\/wp-content\/uploads\/2024\/09\/MadeInDex-Header-Logo.png","@id":"https:\/\/madeindex.org\/de\/made-in-albania\/#organizationLogo","width":177,"height":41,"caption":"MadeInDex Logo"},"image":{"@id":"https:\/\/madeindex.org\/de\/made-in-albania\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/madeindex.org\/de\/made-in-albania\/#webpage","url":"https:\/\/madeindex.org\/de\/made-in-albania\/","name":"Made in Albania - MadeInDex","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/madeindex.org\/de\/#website"},"breadcrumb":{"@id":"https:\/\/madeindex.org\/de\/made-in-albania\/#breadcrumblist"},"datePublished":"2024-10-05T09:23:00+00:00","dateModified":"2024-10-05T09:23:00+00:00"},{"@type":"WebSite","@id":"https:\/\/madeindex.org\/de\/#website","url":"https:\/\/madeindex.org\/de\/","name":"MadeInDex","description":"Der Nachhaltigkeitsindex","inLanguage":"de-DE","publisher":{"@id":"https:\/\/madeindex.org\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"MadeInDex - Der Nachhaltigkeitsindex","og:type":"article","og:title":"Made in Albania - MadeInDex","og:url":"https:\/\/madeindex.org\/de\/made-in-albania\/","og:image":"https:\/\/madeindex.org\/de\/wp-content\/uploads\/2024\/09\/MadeInDex-Header-Logo.png","og:image:secure_url":"https:\/\/madeindex.org\/de\/wp-content\/uploads\/2024\/09\/MadeInDex-Header-Logo.png","article:published_time":"2024-10-05T09:23:00+00:00","article:modified_time":"2024-10-05T09:23:00+00:00","twitter:card":"summary_large_image","twitter:title":"Made in Albania - MadeInDex","twitter:image":"https:\/\/madeindex.org\/de\/wp-content\/uploads\/2024\/09\/MadeInDex-Header-Logo.png"},"aioseo_meta_data":{"post_id":"257","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-10-05 09:34:33","updated":"2025-06-04 09:25:53","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/madeindex.org\/de\" title=\"Zu Hause\">Zu Hause<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMade in Albania\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Zu Hause","link":"https:\/\/madeindex.org\/de"},{"label":"Made in Albania","link":"https:\/\/madeindex.org\/de\/made-in-albania\/"}],"_links":{"self":[{"href":"https:\/\/madeindex.org\/de\/wp-json\/wp\/v2\/pages\/257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/madeindex.org\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/madeindex.org\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/madeindex.org\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/madeindex.org\/de\/wp-json\/wp\/v2\/comments?post=257"}],"version-history":[{"count":1,"href":"https:\/\/madeindex.org\/de\/wp-json\/wp\/v2\/pages\/257\/revisions"}],"predecessor-version":[{"id":308,"href":"https:\/\/madeindex.org\/de\/wp-json\/wp\/v2\/pages\/257\/revisions\/308"}],"wp:attachment":[{"href":"https:\/\/madeindex.org\/de\/wp-json\/wp\/v2\/media?parent=257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}